


{"id":24424,"date":"2025-12-12T12:51:18","date_gmt":"2025-12-12T11:51:18","guid":{"rendered":"https:\/\/loisium.mac-it.at\/history\/"},"modified":"2026-06-15T11:53:36","modified_gmt":"2026-06-15T09:53:36","slug":"history","status":"publish","type":"page","link":"https:\/\/loisium.mac-it.at\/en\/history\/","title":{"rendered":"History"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"24424\" class=\"elementor elementor-24424 elementor-22770\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c1be05 e-flex e-con-boxed sc_layouts_column_icons_position_left e-con e-parent\" data-id=\"6c1be05\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb8de5c sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"eb8de5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">History<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b899c2b sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"b899c2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The Origins of LOISIUM Wine World\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-167c6689 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"167c6689\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1546fcc sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"1546fcc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-587154ae sc_height_huge sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"587154ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b995d27 elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"2b995d27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div\t\tclass=\"sc_title sc_title_default\" ><span class=\"sc_item_subtitle sc_title_subtitle sc_item_subtitle_above sc_item_title_style_default\">Steininger world of wine<\/span><h1 class=\"sc_item_title sc_title_title sc_item_title_style_default sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">The creation of the LOISIUM WineWorld - from an idea to a place of experience<\/span><\/h1><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44f59cf9 elementor-widget-divider--view-line sc_fly_static elementor-widget elementor-widget-divider\" data-id=\"44f59cf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-animation-type=\"block\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-32476d35 elementor-section-full_width elementor-section-height-default elementor-section-height-default animation_type_block sc_fly_static elementor-invisible\" data-id=\"32476d35\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fermentio-fadeinup&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3bec1c97 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"3bec1c97\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71c9c68f num-hover sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"71c9c68f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">1998<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a368d6c sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"a368d6c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16fc1ba7 elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"16fc1ba7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div\t\tclass=\"sc_title sc_title_default\" ><h3 class=\"sc_item_title sc_title_title sc_item_title_style_default sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">The spark - A glass of wine and a chat<\/span><\/h3><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7f466955 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"7f466955\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d4e8639 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"6d4e8639\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Three families from Langenlois\u2014the Haimerls, the Nidetzkys, and the Steininger\u2014sit together over a glass of Gr\u00fcner Veltliner and discuss the future of viticulture.<br\/>From this intimate evening, the idea was born to make the region\u2019s unique wine cellars and wine culture accessible to everyone.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-1529722 elementor-widget-divider--view-line sc_fly_static elementor-widget elementor-widget-divider\" data-id=\"1529722\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-animation-type=\"block\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-5da200d2 elementor-section-full_width elementor-section-height-default elementor-section-height-default animation_type_block sc_fly_static elementor-invisible\" data-id=\"5da200d2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fermentio-fadeinup&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-280f6339 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"280f6339\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b3487c7 num-hover sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"1b3487c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">1999\u20132002\n<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5a84c405 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"5a84c405\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c08c7e3 elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"3c08c7e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div\t\tclass=\"sc_title sc_title_default\" ><h3 class=\"sc_item_title sc_title_title sc_item_title_style_default sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">The vision - combining tradition and modernity<\/span><\/h3><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b5b4758 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"b5b4758\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e11bfcb sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"3e11bfcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">The conversation about the cellars\u2014which are more than 900 years old\u2014the craftsmanship, and the passion for wine grows more intense.<br\/>It becomes increasingly clear: these treasures are meant to be shared.<\/p><p class=\"p1\">The decision is made to open up the historic cellars and integrate them with modern architecture. Working with internationally renowned architect Steven Holl, a bold concept is developed that bridges tradition and innovation. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-60e29c4b elementor-widget-divider--view-line sc_fly_static elementor-widget elementor-widget-divider\" data-id=\"60e29c4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-animation-type=\"block\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-6dcc01da elementor-section-full_width elementor-section-height-default elementor-section-height-default animation_type_block sc_fly_static elementor-invisible\" data-id=\"6dcc01da\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fermentio-fadeinup&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-48993e8f sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"48993e8f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2da64bde num-hover sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"2da64bde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">2003<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1183f3d4 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"1183f3d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ef99a94 elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"4ef99a94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div\t\tclass=\"sc_title sc_title_default\" ><h3 class=\"sc_item_title sc_title_title sc_item_title_style_default sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">The Grand Opening \u2013 A Place for People to Gather Takes Shape\n<\/span><\/h3><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-56414810 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"56414810\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26daa565 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"26daa565\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">LOISIUM Weinwelt has opened its doors.<br\/>Since then, visitors have been able to immerse themselves in a unique experience centered on wine, history, and culture.<\/p><p class=\"p1\">The historic cellars are combined with modern architecture, bringing the identity of the Kamptal to life in a unique way.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-538eff8 elementor-widget-divider--view-line sc_fly_static elementor-widget elementor-widget-divider\" data-id=\"538eff8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-animation-type=\"block\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-94eb95e elementor-section-full_width elementor-section-height-default elementor-section-height-default animation_type_block sc_fly_static elementor-invisible\" data-id=\"94eb95e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fermentio-fadeinup&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c3a274d sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"c3a274d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec69387 num-hover sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"ec69387\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">2025<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a9c130f sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"a9c130f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f00d117 elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"f00d117\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div\t\tclass=\"sc_title sc_title_default\" ><h3 class=\"sc_item_title sc_title_title sc_item_title_style_default sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">Steininger Loisium Wine World<\/span><\/h3><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b55540e sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"b55540e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6353da sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"f6353da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">On September 1, 2025, a new and significant chapter began for the wine world in Langenlois: With the lease taken over by Tuula Nidetzky, this labor of love\u2014which had grown over many years\u2014was deliberately placed in the hands of the Steininger winemaking family, who are not only deeply rooted in the region but have also been closely connected to the wine world from the very beginning. The LOISIUM Weinwelt became the Steininger Loisium Weinwelt and is managed by the two daughters, Lisa Steininger-Fonseca and Eva Steininger. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cf8155 elementor-widget-divider--view-line sc_fly_static elementor-widget elementor-widget-divider\" data-id=\"1cf8155\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-animation-type=\"block\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-b0783d0 elementor-section-full_width elementor-section-height-default elementor-section-height-default animation_type_block sc_fly_static elementor-invisible\" data-id=\"b0783d0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fermentio-fadeinup&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a656331 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"a656331\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39277d7 elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"39277d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><strong>What began as a conversation among friends has now become an internationally renowned gathering place.<\/strong><\/p><p class=\"p1\">The Steininger family has a clear vision: The Steininger Wine World is meant to be an open, vibrant place\u2014for guests from all over the world as well as for locals. A place where you can linger, discover, enjoy, and strike up a conversation. A place where wine is not just tasted, but understood and experienced.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-25afcb16 elementor-widget-divider--view-line sc_fly_static elementor-widget elementor-widget-divider\" data-id=\"25afcb16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5002804b sc_height_huge sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"5002804b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24816967 elementor-section-full_width elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"24816967\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-628be532 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"628be532\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5ef73713 elementor-section-full_width elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"5ef73713\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div data-animation-type=\"block\" class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-62d58407 sc_content_align_inherit sc_layouts_column_icons_position_left animation_type_block sc_fly_static elementor-invisible\" data-id=\"62d58407\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fermentio-fadeinup&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18848ed2 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"18848ed2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-72fb5162 sc_inner_width_1_2 sc-tablet_inner_width_none sc_content_align_left sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"72fb5162\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3db32590 sc_height_huge sc_layouts_hide_on_mobile sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"3db32590\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f9bbb72 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"5f9bbb72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">The LOISIUM WeinWelt did not begin with a grand master plan, but with a simple moment, as so often happens in Langenlois: Three friendly and neighboring families, Haimerl, Nidetzky and Steininger, sat together over a glass of Gr\u00fcner Veltliner and talked about the future of viticulture in their homeland. This conversation turned into an idea, and the idea turned into a vision: the special history of the Langenlois cellar corridors and the culture of wine were to be given a place where they could be felt and experienced by everyone. <\/p><p class=\"p1\">The longer we talked about the centuries-old background, craftsmanship, tradition and passion for wine, the clearer it became: These treasures should be shared. This led to the decision to open up the historic cellars and combine them with modern architecture. The decision to entrust Steven Holl with the design was an expression of this aspiration: to show courage, allow new things to happen and at the same time remain deeply rooted in the region.  <\/p><p class=\"p1\">The LOISIUM WeinWelt became a reality in 2003. Since then, visitors have been immersed in an experience that tells the story of viticulture and reflects the identity of the Kamptal. What began as a personal moment between friends is now a lively meeting place where wine, culture and a piece of Langenlois lifestyle come together.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-255bdb52 sc_height_huge sc_layouts_hide_on_mobile sc_layouts_hide_on_tablet sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"255bdb52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd9475e elementor-section-full_width elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"bd9475e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-05ff147 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"05ff147\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94f9277 sc_height_huge sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"94f9277\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>History The Origins of LOISIUM Wine World Steininger world of wine The creation of the LOISIUM WineWorld &#8211; from an idea to a place of experience 1998 The spark &#8211;&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-24424","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/loisium.mac-it.at\/en\/wp-json\/wp\/v2\/pages\/24424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loisium.mac-it.at\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/loisium.mac-it.at\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/loisium.mac-it.at\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/loisium.mac-it.at\/en\/wp-json\/wp\/v2\/comments?post=24424"}],"version-history":[{"count":4,"href":"https:\/\/loisium.mac-it.at\/en\/wp-json\/wp\/v2\/pages\/24424\/revisions"}],"predecessor-version":[{"id":25218,"href":"https:\/\/loisium.mac-it.at\/en\/wp-json\/wp\/v2\/pages\/24424\/revisions\/25218"}],"wp:attachment":[{"href":"https:\/\/loisium.mac-it.at\/en\/wp-json\/wp\/v2\/media?parent=24424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}